{"id":56,"count":260,"description":"","link":"https:\/\/ftik.uin-malang.ac.id\/en\/category\/berita\/akademik\/","name":"Akademik","slug":"akademik","taxonomy":"category","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/ftik.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/categories\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ftik.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ftik.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/ftik.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/categories\/3"}],"wp:post_type":[{"href":"https:\/\/ftik.uin-malang.ac.id\/en\/wp-json\/wp\/v2\/posts?categories=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}